{"id":48117,"date":"2022-06-10T16:42:11","date_gmt":"2022-06-10T14:42:11","guid":{"rendered":"https:\/\/moovago.com\/senza-categoria\/come-organizza-la-sua-mappatura-delle-vendite\/"},"modified":"2025-11-26T09:02:29","modified_gmt":"2025-11-26T08:02:29","slug":"come-organizza-la-sua-mappatura-delle-vendite","status":"publish","type":"post","link":"https:\/\/moovago.com\/it\/giro-commerciale\/come-organizza-la-sua-mappatura-delle-vendite\/","title":{"rendered":"Come organizza la sua mappatura delle vendite?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"48117\" class=\"elementor elementor-48117 elementor-11876\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5587173 e-con-full e-flex e-con e-parent\" data-id=\"5587173\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52f3180 elementor-widget elementor-widget-text-editor\" data-id=\"52f3180\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La mappatura delle vendite \u00e8 uno <b>strumento essenziale che ogni commerciale sul campo dovrebbe avere<\/b>.<\/p><p>I vantaggi di una buona mappatura commerciale sono molteplici:  <\/p><ul><li><b>Posizionare e visualizzare i suoi clienti su una mappa<\/b>,<\/li><li>Identifichi le aree in cui si concentrano i suoi clienti e i suoi potenziali clienti,<\/li><li>Identificare le aree in cui la sua forza vendita non \u00e8 attualmente presente (cio\u00e8 le opportunit\u00e0 di sviluppo delle vendite potenziali),<\/li><li>Dare priorit\u00e0 alle visite dei clienti,<\/li><li><b>Trovi dei potenziali clienti vicini a lei<\/b> quando \u00e8 in giro,<\/li><li><a href=\"https:\/\/moovago.com\/blog\/tournee-commerciale\/organiser-plan-de-tournee-commerciale\/\">Pianifichi un giro di vendite<\/a> e lo ottimizzi determinando il percorso migliore,<\/li><li>Completi i suoi giri identificando le opportunit\u00e0 di visita sul suo percorso,<\/li><li><b>Definisca le zone commerciali e ottimizzi i settori commerciali<\/b> per rafforzare la sua presenza sul territorio&#8230;<\/li><\/ul><div> <\/div><div>Vuole sapere come creare la sua mappa delle vendite in soli 4 passi? Allora inizi! <\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-428a138 elementor-widget elementor-widget-heading\" data-id=\"428a138\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Che cos'\u00e8 la mappatura commerciale?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17f678e elementor-widget elementor-widget-text-editor\" data-id=\"17f678e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var( --e-global-color-49a30e0 );\">Per mappatura commerciale si intende <\/span><b style=\"color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var( --e-global-color-49a30e0 );\">la creazione di una mappa su cui sono posizionati i clienti, i prospect e\/o i contatti<\/b><span style=\"color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var( --e-global-color-49a30e0 );\"><b> di un venditore<\/b><\/span><span style=\"color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var( --e-global-color-49a30e0 );\">un team di vendita o un&#8217;intera azienda.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d846e56 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"d846e56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Mappa geografica VS mappa dei processi aziendali<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">L'altro significato di cartografia commerciale (o mappa commerciale) pu\u00f2 anche riferirsi alla mappa \"schematica\" che rappresenta i processi commerciali all'interno di un'azienda.<\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a83fec6 elementor-widget elementor-widget-text-editor\" data-id=\"a83fec6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si noti che la sua <strong>mappa delle vendite<\/strong> pu\u00f2 essere utilizzata anche come <a href=\"https:\/\/moovago.com\/it\/giro-commerciale\/come-organizza-la-sua-mappa-di-prospezione\/\">mappa di prospezione<\/a>. Lo scopo di questa mappa \u00e8 quello di aiutarla a trovare i potenziali clienti e a seguirli sul campo. \u00c8 uno strumento utile per individuare le aziende da contattare sul campo.  <\/p><p>In altri casi, la mappatura commerciale pu\u00f2 anche servire come <b>mappa dei settori commerciali<\/b>. Fornendo una <b>visione geografica dei settori dei vari rappresentanti commerciali<\/b> di un&#8217;azienda, quest&#8217;ultima pu\u00f2 decidere di aprire nuove zone di prospezione delle vendite, ridefinire i territori dei suoi rappresentanti commerciali o scoprire come gestire al meglio le sue risorse. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ac4353 elementor-widget elementor-widget-heading\" data-id=\"5ac4353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Geocodifica, il segreto della mappatura commerciale<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d471b1 elementor-widget elementor-widget-text-editor\" data-id=\"7d471b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Oggi la mappatura commerciale si basa su strumenti digitali.<\/p><p>Grazie alla <b>geocodifica<\/b>,<b> gli indirizzi postali dei suoi contatti vengono convertiti in coordinate geografiche<\/b> e posizionati su una mappa digitale. Ogni cliente e prospect viene posizionato sulla mappa sotto forma di marcatori. <\/p><p>Pu\u00f2 sembrare un po&#8217; complicato, ma stia tranquillo: tutti i software di mappatura commerciali svolgono questo lavoro per lei, utilizzando un file Excel contenente il nome del suo cliente e l&#8217;indirizzo postale completo. Questa \u00e8 tecnologia per lei! <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f804ec3 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"f804ec3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Mappatura commerciale e pianificazione del percorso<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\"><p><\/p><p>Oltre a visualizzare semplicemente il portafoglio clienti su una mappa, la mappatura delle vendite consente ai venditori itineranti di prendere decisioni informate sull'<b> organizzazione dei loro giri e sull'ottimizzazione dei loro itinerari<\/b>. Pianificando con attenzione i loro giri e rimanendo sufficientemente flessibili per tenere conto delle opportunit\u00e0 di visita nelle vicinanze, delle condizioni del traffico e delle cancellazioni dell'ultimo minuto, i venditori saranno in grado di essere efficaci anche in caso di circostanze impreviste. <\/p>\n\ud83d\udc49 Per ulteriori informazioni, consulti :  <b><u><a style=\"color:#00520F\" href=\"https:\/\/moovago.com\/blog\/tournee-commerciale\/organiser-plan-de-tournee-commerciale\/\">Come organizzare giri di vendita efficaci<\/a><\/u><\/b><\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f3c2dd elementor-widget elementor-widget-heading\" data-id=\"4f3c2dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Esempio di mappatura commerciale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3a0f1c elementor-widget elementor-widget-text-editor\" data-id=\"f3a0f1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prima di andare avanti, diamo un&#8217;occhiata a un esempio realizzato con un<a href=\"https:\/\/moovago.com\/logiciel-cartographie-commerciale\/\"> software di mappatura commerciale<\/a>.<\/p><p>Sulla mappa di Moovago qui sotto, <strong>ogni marcatore rappresenta l&#8217;azienda <\/strong>di un cliente o di un potenziale cliente. Nel nostro esempio, i nostri contatti si trovano in Francia, ma tenga presente che potrebbero essere ovunque nel mondo! <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1bec63 elementor-widget elementor-widget-image\" data-id=\"c1bec63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"620\" src=\"https:\/\/moovago.com\/wp-content\/uploads\/2024\/02\/logiciel-de-cartographique-commerciale.png\" class=\"attachment-full size-full wp-image-43369\" alt=\"software di mappatura commerciale\" srcset=\"https:\/\/moovago.com\/wp-content\/uploads\/2024\/02\/logiciel-de-cartographique-commerciale.png 900w, https:\/\/moovago.com\/wp-content\/uploads\/2024\/02\/logiciel-de-cartographique-commerciale-300x207.png 300w, https:\/\/moovago.com\/wp-content\/uploads\/2024\/02\/logiciel-de-cartographique-commerciale-768x529.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"Moovago, application commerciaux, CRM, ERP, PGI, GRC\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad59686 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"ad59686\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Ha notato che la mappa Moovago non si limita a visualizzare i punti su una mappa?<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">Molte altre interazioni sono possibili utilizzando la mappa Moovago:\n<ul><li>Conosce immediatamente lo stato di un marcatore (cliente o prospect) grazie ai colori,\n<\/li><li>Filtrare i marcatori facendo clic su un tipo di marcatore nella legenda,\n<\/li><li>Clicchi su un contatto per accedere alla sua scheda dettagliata,\n<\/li><li>Vede quali contatti hanno un appuntamento o un'attivit\u00e0 programmata,<br><\/li>\n<li>Aggiunga i suoi contatti a un giro in 2 clic,<\/li>\n<li>Visualizzare i diversi settori commerciali,<\/li>\n<li>E persino trovare nuovi potenziali clienti grazie alla ricerca integrata su Google.<\/li><\/ul><\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f041bde elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f041bde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/moovago.com\/it\/giro-commerciale\/come-organizza-la-sua-mappatura-delle-vendite\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Crei la sua mappa aziendale (e molto altro) con Moovago<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f752f65 elementor-widget elementor-widget-heading\" data-id=\"f752f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Creare la sua mappa delle vendite in 4 passi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fcf6ab elementor-widget elementor-widget-heading\" data-id=\"9fcf6ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Passo 1: fare il punto sulle sue esigenze<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a7dd66 elementor-widget elementor-widget-text-editor\" data-id=\"7a7dd66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Primo passo: si chieda qual \u00e8 l&#8217;obiettivo di questa mappatura aziendale. Cosa intende fare con questa mappa? <\/p><p style=\"text-align: left;\"><span style=\"background-color: var( --e-global-color-49a30e0 ); color: var( --e-global-color-text );\"><b>Ha semplicemente bisogno di vedere i suoi contatti su una mappa<\/b> (nel qual caso le consigliamo alternative semplicistiche e gratuite come <a href=\"https:\/\/www.google.com\/maps\/d\/u\/0\/\" target=\"_blank\" rel=\"noopener\">Google My Maps<\/a>) o <b>ha esigenze pi\u00f9 specifiche<\/b>?<\/span><\/p><p style=\"text-align: left;\"><span style=\"background-color: var( --e-global-color-49a30e0 ); color: var( --e-global-color-text );\">Quando i potenziali clienti contattano<\/span><span style=\"background-color: var( --e-global-color-49a30e0 ); color: var( --e-global-color-text );\"> Moovago, ecco cosa ci dicono pi\u00f9 spesso (si senta libero di confrontare questi punti con il suo elenco di esigenze):<\/span><\/p><ul><li><span style=\"background-color: var( --e-global-color-49a30e0 ); color: var( --e-global-color-text ); text-align: var(--text-align);\">Classificare e distinguere <b>i contatti come prospect\/clienti\/sospetti<\/b>,<\/span><\/li><li><span style=\"background-color: var( --e-global-color-49a30e0 ); color: var( --e-global-color-text ); text-align: var(--text-align);\">Utilizzi la mappa per <b>pianificare i giri di vendita<\/b>,<\/span><\/li><li><span style=\"background-color: var( --e-global-color-49a30e0 ); color: var( --e-global-color-text ); text-align: var(--text-align);\">Filtrare le informazioni sulla mappa in base a <b>specifici criteri di segmentazione<\/b> (fatturato, origine del contatto, marchio, settore, ecc,)<\/span><\/li><li>Sapere quali clienti su questa mappa non ha visto di recente (per dare priorit\u00e0 alle sue visite),<\/li><li>Accedere alla cronologia del follow-up dei clienti\/prospect (note, compiti, eventi, appuntamenti, ecc.),<\/li><li><b>Popola questo database<\/b> con nuovi elementi di monitoraggio (rapporti, compiti, eventi, appuntamenti, ecc.) e\/o nuove voci (nuovi clienti, clienti persi, nuove prospettive, ecc.).<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cd8af8 elementor-widget elementor-widget-heading\" data-id=\"7cd8af8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Passo 2: trovare il software di mappatura pi\u00f9 adatto alle sue esigenze<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c1c276 elementor-widget elementor-widget-text-editor\" data-id=\"6c1c276\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A seconda delle risposte a tutte queste domande, sar\u00e0 pi\u00f9 facile per lei determinare <strong>quali funzioni desidera dal suo software di mappatura<\/strong> (oltre alla semplice visualizzazione dei suoi clienti su una mappa). Ad esempio, potrebbe aver bisogno di un elenco clienti o persino di un <a href=\"https:\/\/moovago.com\/blog\/crm\/crm-customer\/\">CRM<\/a>. <\/p><p>Questo software non solo le permette di interagire con i marcatori sulla carta, ma le consente anche di consultare i registri dei suoi clienti e prospect, e di accedere alla cronologia degli appuntamenti, ai rapporti e alle note.<\/p><p>Altri utenti potrebbero dover mappare i loro settori commerciali utilizzando un <strong>software di settorizzazione commerciale<\/strong>.<\/p><p>Altri strumenti le consentono persino di creare e ottimizzare i suoi giri di vendita.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e88a80 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"9e88a80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Alcuni software professionali da scoprire:  <\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\"><ul>\n \t<li><a href=\"https:\/\/moovago.com\/it\/tariffe\/\">Moovago<\/a> (strumento CRM, giro e tracciamento dei clienti): da 23,9 euro\/mese,<\/li>\n \t<li><a href=\"https:\/\/www.badgermapping.com\/fr\/\" target=\"_blank\" rel=\"noopener\">Badger<\/a> (strumento per il giro in inglese): a partire da 58 euro\/mese,<\/li>\n \t<li><a href=\"https:\/\/www.portatour.com\/pricing\/\" target=\"_blank\" rel=\"noopener\">Portatour<\/a> (strumento per il giro): da 79,95 euro\/mese.<\/li>\n<\/ul><\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e03131 elementor-widget elementor-widget-heading\" data-id=\"2e03131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Passo 3: preparare un file Excel per importare i suoi dati<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-611c7d1 elementor-widget elementor-widget-heading\" data-id=\"611c7d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Quali dati devono essere inclusi nel file di importazione Excel?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53802d3 elementor-widget elementor-widget-text-editor\" data-id=\"53802d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per consentire al software di mappatura commerciale di posizionare i suoi contatti sulla mappa, deve <b>dirgli dove si trova ogni cliente e prospect<\/b>. Questi dati devono essere strutturati in un file che il software pu\u00f2 leggere e interpretare per eseguire la geocodifica. Questo file \u00e8 spesso un foglio di calcolo Excel.  <\/p><p>Affinch\u00e9 l&#8217;importazione abbia luogo, il suo file deve includere almeno un file :<\/p><ul><li>  Una <b>colonna con il nome del suo prospect o cliente<\/b>,<\/li><li>  Una <b>colonna per ogni informazione dell&#8217;indirizzo<\/b>: numero e nome della via, citt\u00e0, codice postale, Paese.<\/li><\/ul><div> <\/div><div>Tuttavia, il tipo di software scelto determiner\u00e0 la quantit\u00e0 di dati da fornire. Un CRM le chieder\u00e0 certamente di fornire il maggior numero di informazioni possibili: nome, indirizzo, stato del contatto, criteri di segmentazione, dettagli del contatto, ecc. <\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-926936d elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"926936d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Il nostro consiglio<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">Contatti l'editore del suo software per un elenco di tutti i dati che deve importare.<\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-717eee3 elementor-widget elementor-widget-heading\" data-id=\"717eee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Come si prepara questo file di importazione?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-893a540 elementor-widget elementor-widget-text-editor\" data-id=\"893a540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se <b>gestisce il suo portafoglio clienti utilizzando Excel<\/b> (o un altro programma di foglio elettronico), <b>\u00e8 sufficiente copiare e incollare i dati necessari<\/b> in un file Excel vuoto.  <\/p><p>Ogni riga corrisponder\u00e0 a un contatto (un marcatore sulla mappa) e ogni colonna a un tipo di informazione (nome del contatto, via, citt\u00e0, codice postale, Paese, telefono, tipo di contatto, ecc.)<\/p><p>Se non dispone di un file di questo tipo, ma sta gi\u00e0 lavorando con un sistema ERP o CRM, <strong>esporti semplicemente i suoi dati in formato Excel dal suo software attuale<\/strong>. Si assicuri che il file Excel contenga tutti i dati necessari. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6bb4f5 elementor-widget elementor-widget-heading\" data-id=\"f6bb4f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Passo 4: importare nel suo software di mappatura<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f144703 elementor-widget elementor-widget-text-editor\" data-id=\"f144703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Come spiegato sopra, tutto ci\u00f2 che deve fare \u00e8<b> trascinare e rilasciare un file Excel nella finestra di importazione del suo software di mappatura<\/b>, in modo che possa procedere con la geocodifica.<\/p><p>In pochi istanti, lo strumento trasforma i dati in punti su una mappa interattiva e dinamica!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ab1eba e-con-full e-flex e-con e-child\" data-id=\"5ab1eba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61a6c3c elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"61a6c3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"550\" height=\"720\" src=\"https:\/\/moovago.com\/wp-content\/uploads\/2024\/01\/geocoding-pour-commerciaux.jpg\" class=\"attachment-medium_large size-medium_large wp-image-43305\" alt=\"esempio di piano di giro\" srcset=\"https:\/\/moovago.com\/wp-content\/uploads\/2024\/01\/geocoding-pour-commerciaux.jpg 550w, https:\/\/moovago.com\/wp-content\/uploads\/2024\/01\/geocoding-pour-commerciaux-229x300.jpg 229w\" sizes=\"(max-width: 550px) 100vw, 550px\" title=\"Moovago, application commerciaux, CRM, ERP, PGI, GRC\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e823874 e-flex e-con-boxed e-con e-child\" data-id=\"e823874\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24a7c52 elementor-widget elementor-widget-heading\" data-id=\"24a7c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Crei la sua mappa delle vendite dal suo file clienti in Excel.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b634c4 elementor-widget elementor-widget-text-editor\" data-id=\"7b634c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Importi il suo file Excel in Moovago e visualizzi tutti i suoi clienti e potenziali clienti su una mappa interattiva di Google.<\/p><p><strong>BONUS: cerchi le aziende su Google e le registri nel suo database per incrementare la sua attivit\u00e0 di prospezione!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81ecafb elementor-align-center elementor-widget elementor-widget-button\" data-id=\"81ecafb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/moovago.com\/essai-gratuit\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Provi Moovago gratuitamente<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be73af3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"be73af3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/moovago.com\/it\/funzionalita-mappa\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scopra di pi\u00f9 sulla mappa Moovago<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4e56f elementor-widget elementor-widget-heading\" data-id=\"7d4e56f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mantenere aggiornata la sua mappa delle vendite: le migliori pratiche<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62d7efd elementor-widget elementor-widget-text-editor\" data-id=\"62d7efd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una volta importato il suo database clienti, \u00e8 essenziale che <b>continui a popolarlo e aggiornarlo<\/b>.<\/p><p>Se perde un cliente (non glielo auguriamo), dovr\u00e0 modificare lo stato di un contatto di conseguenza. Lo stesso vale se il suo portafoglio clienti cresce o se converte i potenziali clienti in clienti. <\/p><p>Se non lo fa? Rischia di avvicinarsi a un contatto che pensa sia un potenziale cliente&#8230; quando in realt\u00e0 \u00e8 gi\u00e0 cliente da tempo. In breve, <b>le sue<\/b> <b>azioni di vendita non possono essere accurate se si basano su dati falsi<\/b>.    <\/p><p>Ma come si fa a mantenere questi dati aggiornati?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2bcc4b elementor-widget elementor-widget-heading\" data-id=\"f2bcc4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Importazione di nuovi dati<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf7f388 elementor-widget elementor-widget-text-editor\" data-id=\"bf7f388\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per mantenere aggiornata la sua mappa delle vendite, la prima opzione \u00e8 quella di <b>eseguire un&#8217;importazione di massa dei dati tramite un file Excel<\/b>. Tutti i nuovi contatti saranno aggiunti ai marcatori gi\u00e0 presenti sulla sua mappa delle vendite. <\/p>\n<p>La buona notizia \u00e8 che, per la maggior parte dei pacchetti software, l&#8217;operazione sar\u00e0 la stessa descritta sopra per la sua prima importazione. La struttura del file di importazione sar\u00e0 identica, in particolare per i nomi delle colonne. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b7278 elementor-widget elementor-widget-heading\" data-id=\"e1b7278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Popola la sua mappa delle vendite man mano che procede<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4bd967 elementor-widget elementor-widget-text-editor\" data-id=\"f4bd967\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: var( --e-global-color-text ); text-align: var(--text-align); background-color: var( --e-global-color-49a30e0 );\">Pu\u00f2 anche modificare i dati manualmente.<\/span> In altre parole, pu\u00f2<b>apportare le modifiche tramite l&#8217;interfaccia dello strumento di mappatura<\/b>, del CRM o dello strumento di giro.<\/p><p>Questa tecnica \u00e8 pi\u00f9 adatta se pu\u00f2 apportare queste modifiche in modo discontinuo. Ad esempio, potrebbe convalidare un preventivo con un potenziale cliente e poi cogliere l&#8217;occasione per cambiare lo stato di questo contatto nel suo CRM da potenziale a cliente. <\/p><p>La maggior parte dei rappresentanti di vendita che utilizzano Moovago hanno fatto questa scelta per la <strong>gestione quotidiana del loro portafoglio<\/strong> clienti e prospect.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-944d5e9 elementor-widget elementor-widget-heading\" data-id=\"944d5e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Utilizzo di un'API<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-481ddfa elementor-widget elementor-widget-text-editor\" data-id=\"481ddfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se vuole che i suoi dati siano sempre accurati, senza doverli importare o modificare manualmente, c&#8217;\u00e8 anche la soluzione API.&nbsp;<\/p>\n<p>In parole povere, un&#8217;API aperta consente di collegare tra loro due software. In questo caso, <b>l&#8217;API consentir\u00e0 di inviare dati da un sistema ERP o CRM al suo software di mappatura<\/b>. Se l&#8217;azienda che la assume o le d\u00e0 mandato alimenta il primo strumento, tutte le modifiche saranno trasferite alla sua mappa commerciale.  <\/p>\n<p>Un vero e proprio risparmio di tempo per il personale di vendita!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94af84c elementor-widget elementor-widget-heading\" data-id=\"94af84c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Come si sceglie il giusto software di mappatura aziendale?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fd6c16 elementor-widget elementor-widget-text-editor\" data-id=\"6fd6c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ancora una volta, la scelta del software di mappatura o dell&#8217;<a href=\"https:\/\/moovago.com\/logiciel-planification-tournee\/\">applicazione di mappatura aziendale<\/a> dipender\u00e0 dalle sue esigenze, che a loro volta sono direttamente guidate dai suoi obiettivi aziendali.<\/p><p>Ad esempio, Moovago ha posto la mappatura delle vendite al centro del suo software, consentendo al personale commerciale sul campo di <b>visualizzare il proprio portafoglio su una mappa<\/b>, oltre a <b>pianificare i giri<\/b> e a <b>seguire le vendite con facilit\u00e0<\/b>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-510ccfe elementor-widget elementor-widget-heading\" data-id=\"510ccfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Garantire la sicurezza dei suoi dati<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-551ef47 elementor-widget elementor-widget-text-editor\" data-id=\"551ef47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Che scelga una soluzione gratuita o a pagamento, verifichi sempre le <b>misure di sicurezza adottate dall&#8217;editore del software<\/b>.  <\/p><p>Il problema di scegliere di lavorare con uno strumento come <a href=\"https:\/\/www.google.com\/maps\" target=\"_blank\" rel=\"noopener\">Google My Maps<\/a> \u00e8 che nessuno pu\u00f2 garantire che i suoi dati rimangano riservati. Sarebbe spiacevole se i suoi dati fossero esposti a causa di un errore di configurazione o di una falla nella sicurezza. <\/p><p>Moovago, invece, salva i suoi dati su server sicuri ospitati in Francia. Ci assicuriamo che i suoi dati siano protetti in conformit\u00e0 alle <strong>raccomandazioni della legge francese, della CNIL e del RPGD<\/strong>. La combinazione perfetta per una buona notte di sonno!  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7985ce9 elementor-widget elementor-widget-heading\" data-id=\"7985ce9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Chieda una prova prima di prendere un impegno<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59288a4 elementor-widget elementor-widget-text-editor\" data-id=\"59288a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maggior parte dei software di mappatura commerciali le consentiranno di <b>testare gratuitamente il loro strumento per un certo periodo<\/b>. Lo stesso vale per i CRM o i pianificatori di giri. <\/p><p>Testare un software \u00e8 il modo migliore per assicurarsi che soddisfi le sue esigenze sotto ogni aspetto.<\/p><p>Naturalmente, <b>non deve prendere alcun impegno per iniziare questo periodo di prova<\/b>! Moovago, ad esempio, offre un periodo di prova gratuito di 15 giorni<a href=\"https:\/\/moovago.com\/essai-gratuit\/\">(disponibile registrandosi qui<\/a>).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92a2145 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"92a2145\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Utilizza MapPoint come software di mappatura?<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">Scopra alcuni <a href=\"https:\/\/moovago.com\/blog\/tournee-commerciale\/alternatives-mappoint\/\">strumenti per sostituire MapPoint<\/a>.<\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54fe373 elementor-widget elementor-widget-spacer\" data-id=\"54fe373\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c7c46a elementor-widget elementor-widget-heading\" data-id=\"9c7c46a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Domande frequenti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6897e87 elementor-widget elementor-widget-toggle\" data-id=\"6897e87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-1091\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1091\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Perch\u00e9 mappare i suoi clienti?<\/a>\n\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1091\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1091\"><p>Quando si occupa di vendite, vedere i suoi clienti su una mappa \u00e8 di grande aiuto per <b>fare le scelte giuste di fronte all&#8217;ampiezza del suo portafoglio clienti.<\/b><\/p>\n<p>Ecco alcuni esempi che evidenziano l&#8217;importanza della mappatura aziendale:<\/p>\n<ul>\n<li>Marted\u00ec prossimo devo visitare il mio cliente Tartempion a Bordeaux. Quali altri clienti posso includere nel mio giro quel giorno per ottimizzare il mio itinerario? <\/li>\n<li>Uno dei miei appuntamenti \u00e8 terminato in anticipo. Quale cliente posso andare a trovare per tenermi occupata mentre aspetto il prossimo appuntamento? Ci sono clienti potenziali vicino a me?  <\/li>\n<li>Voglio fare un giro a Bordeaux il marted\u00ec. Quali clienti della regione di Bordeaux potrei includere nel <a href=\"https:\/\/moovago.com\/blog\/tournee-commerciale\/organiser-plan-de-tournee-commerciale\/\">programma di questo tour<\/a>? <\/li>\n<\/ul>\n<div> <\/div>\n<p>Rispondere a queste domande \u00e8 un gioco da ragazzi se ha a disposizione una <b>mappa del cliente sul campo<\/b>!<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-1092\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1092\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00c8 possibile fare a meno del software di mappatura commerciale?<\/a>\n\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1092\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1092\"><p>\u00c8 vero che pu\u00f2 beneficiare di tutti i vantaggi della mappatura delle vendite senza dover pagare un software professionale. Utilizzando strumenti di vendita &#8216;classici&#8217; (Excel, Google Maps, ecc.), pu\u00f2 organizzare giri di vendita, scoprire dove si trova un cliente in base al suo indirizzo e dare priorit\u00e0 agli sforzi di un team di vendita. <\/p>\n<p>Tuttavia, la mappatura commerciale le permette di fare tutto questo:  <\/p>\n<ul>\n<li><b>A colpo d&#8217;occhio<\/b>, semplicemente guardando il suo biglietto da visita,<\/li>\n<li><b>Senza passare ore a filtrare i database dei clienti di Excel<\/b>,<\/li>\n<li>In modo <b>divertente<\/b>, <b>interagendo direttamente<\/b> con i clienti e i potenziali clienti sulla mappa.<\/li>\n<li>E soprattutto, <b>senza dimenticare alcuna informazione<\/b>!<\/li>\n<\/ul>\n<div> <\/div>\n<div> <\/div>\n<div>In breve, un addetto alle vendite con una mappa delle vendite <b>risparmia tempo per lavorare in Excel<\/b>, tempo per <b>pensare<\/b> e <b>molta energia<\/b>, in modo da potersi concentrare sulla sua attivit\u00e0 principale: andare sul campo, seguire i clienti e fare prospezione!<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h2 id=\"elementor-tab-title-1093\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1093\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Perch\u00e9 l'accuratezza geografica \u00e8 fondamentale per una buona mappatura commerciale?<\/a>\n\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1093\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1093\"><p>Pi\u00f9 accurati sono gli indirizzi nel suo file Excel, pi\u00f9 accurata sar\u00e0 la geocodifica.<\/p>\n<p>Al momento dell&#8217;importazione, se fornisce solo la citt\u00e0 in cui si trova l&#8217;azienda di un cliente, il software di mappatura non sar\u00e0 in grado di geolocalizzare il suo cliente nella posizione esatta in cui si trova.<\/p>\n<p>Non \u00e8 molto pratico se intende utilizzare la sua mappatura per effettuare dei giri (e sperare di risparmiare tempo sulla strada e carburante!).  <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf79941 elementor-widget elementor-widget-spacer\" data-id=\"bf79941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-274b5db elementor-widget elementor-widget-heading\" data-id=\"274b5db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I nostri altri consigli per il suo giro di vendite<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf58dfe elementor-grid-2 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"bf58dfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;2&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-48153 post type-post status-publish format-standard has-post-thumbnail hentry category-crm-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/moovago.com\/it\/crm-2\/5-passi-per-organizzare-le-sue-visite-ai-clienti\/\" tabindex=\"-1\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/moovago.com\/wp-content\/uploads\/2022\/06\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Bob-3-1.png\" class=\"attachment-full size-full wp-image-42692\" alt=\"organizzare le visite ai clienti\" title=\"Moovago, application commerciaux, CRM, ERP, PGI, GRC\" srcset=\"https:\/\/moovago.com\/wp-content\/uploads\/2022\/06\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Bob-3-1.png 1024w, https:\/\/moovago.com\/wp-content\/uploads\/2022\/06\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Bob-3-1-300x169.png 300w, https:\/\/moovago.com\/wp-content\/uploads\/2022\/06\/Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Copy-of-Bob-3-1-768x432.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<p class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/moovago.com\/it\/crm-2\/5-passi-per-organizzare-le-sue-visite-ai-clienti\/\">\n\t\t\t\t5 passi per organizzare le sue visite ai clienti\t\t\t<\/a>\n\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-48412 post type-post status-publish format-standard has-post-thumbnail hentry category-giro-commerciale\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/moovago.com\/it\/giro-commerciale\/come-si-ottimizza-un-giro-di-vendite\/\" tabindex=\"-1\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/moovago.com\/wp-content\/uploads\/2023\/10\/Optimiser-tournee-commerciale.jpg\" class=\"attachment-full size-full wp-image-43157\" alt=\"ottimizzare un tour di vendita\" title=\"Moovago, application commerciaux, CRM, ERP, PGI, GRC\" srcset=\"https:\/\/moovago.com\/wp-content\/uploads\/2023\/10\/Optimiser-tournee-commerciale.jpg 1024w, https:\/\/moovago.com\/wp-content\/uploads\/2023\/10\/Optimiser-tournee-commerciale-300x169.jpg 300w, https:\/\/moovago.com\/wp-content\/uploads\/2023\/10\/Optimiser-tournee-commerciale-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<p class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/moovago.com\/it\/giro-commerciale\/come-si-ottimizza-un-giro-di-vendite\/\">\n\t\t\t\tCome si ottimizza un giro di vendite?\t\t\t<\/a>\n\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La mappatura delle vendite \u00e8 uno strumento essenziale che ogni commerciale sul campo dovrebbe avere. I vantaggi di una buona mappatura commerciale sono molteplici: Posizionare<\/p>\n","protected":false},"author":2,"featured_media":42672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[637],"tags":[],"class_list":["post-48117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-giro-commerciale"],"_links":{"self":[{"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/posts\/48117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/comments?post=48117"}],"version-history":[{"count":1,"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/posts\/48117\/revisions"}],"predecessor-version":[{"id":48118,"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/posts\/48117\/revisions\/48118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/media\/42672"}],"wp:attachment":[{"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/media?parent=48117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/categories?post=48117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moovago.com\/it\/wp-json\/wp\/v2\/tags?post=48117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}